{"id":558,"date":"2020-11-07T11:32:08","date_gmt":"2020-11-07T17:32:08","guid":{"rendered":"https:\/\/www.dallassymphony.org\/?page_id=558"},"modified":"2026-07-13T11:07:34","modified_gmt":"2026-07-13T16:07:34","slug":"first-responders-essential-employees","status":"publish","type":"page","link":"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/ticket-info-offers\/first-responders-essential-employees\/","title":{"rendered":"Personal de primera respuesta y empleados esenciales"},"content":{"rendered":"<div\n\tclass=\"subpage__hero bg-black\">\n\n\t<div class=\"img__wrapper d-none d-lg-block\" style=\"background: url(https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386.jpg) top right\/cover no-repeat\"><\/div>\n\n\n\t<div class=\"content__wrapper\">\n\n\t\t<ul class=\"breadcrumbs text-white\">\n\t\t\t<ul class=\"breadcrumbs\">\n    \t<li class=\"breadcrumb__link\">\n\t\t<a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/\">Inicio<\/a>\n\t<\/li>\n    \t<li class=\"breadcrumb__link a-styles\">\n\t\t<a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/\">Conciertos y entradas<\/a>\n\t<\/li>\n    \t<li class=\"breadcrumb__link a-styles\">\n\t\t<a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/ticket-info-offers\/\">Ofertas especiales<\/a>\n\t<\/li>\n    <\/ul>\n\t\t<\/ul>\n\n\t\t<h1 class=\"text-white\">Primeros auxilios y empleados esenciales<\/h1>\n\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1442\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386.jpg\" class=\"d-block d-lg-none w-100\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386.jpg 2560w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-1024x577.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-1536x865.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-2048x1154.jpg 2048w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2024\/08\/dso-10.23.2023-32-2-scaled-e1723059566386-1600x900.jpg 1600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\n\t\t<div class=\"text-blue-3 sans__reg-18\"><p>Los primeros intervinientes y los empleados esenciales pueden recibir un descuento del 50% en las entradas de determinados conciertos de la temporada.<\/p>\n<\/div>\n\n                <a href=\"\" class=\"a-hover text-white\"><\/a>\n        \t<\/div>\n<\/div>\n\n<div class=\"richtext m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-10\">\n\t\t\t\t\n\n<h3 class=\"wp-block-heading\" id=\"h-ticket-availability\">Disponibilidad de billetes<\/h3>\n\n\n\n<p>Los primeros intervinientes y los empleados esenciales pueden recibir un descuento de 50% en las entradas de determinados conciertos de la temporada, presentando su carn\u00e9 de trabajo u otra prueba de empleo en el mostrador de servicios a los visitantes de la DSO o utilizando el c\u00f3digo promocional <strong>FIRST50<\/strong> en el momento de la compra.<\/p>\n\n\n\n<p><em>El <a href=\"https:\/\/www.dallassymphony.org\/es\/explore-the-2026-27-season\/\" data-type=\"post\" data-id=\"29878\">Temporada 2026\/27<\/a> Los conciertos se anunciar\u00e1n el <strong>primera semana de agosto<\/strong>.<\/em><\/p>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La Sinf\u00f3nica de Dallas presenta una serie de conciertos gratuitos para los primeros auxilios y los empleados esenciales. Estas actuaciones son gratuitas para los primeros auxilios, los empleados esenciales y sus familias. <\/p>","protected":false},"author":3,"featured_media":21690,"parent":548,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-558","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/pages\/558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/comments?post=558"}],"version-history":[{"count":3,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/pages\/558\/revisions"}],"predecessor-version":[{"id":32003,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/pages\/558\/revisions\/32003"}],"up":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/pages\/548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media\/21690"}],"wp:attachment":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media?parent=558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}