{"id":29999,"date":"2026-02-26T09:58:00","date_gmt":"2026-02-26T15:58:00","guid":{"rendered":"https:\/\/www.dallassymphony.org\/?post_type=dso_prod_season&#038;p=29999"},"modified":"2026-03-06T18:58:43","modified_gmt":"2026-03-07T00:58:43","slug":"harry-potter-and-the-half-blood-prince-in-concert","status":"publish","type":"dso_prod_season","link":"https:\/\/www.dallassymphony.org\/es\/productions\/harry-potter-and-the-half-blood-prince-in-concert\/","title":{"rendered":"Harry Potter y el pr\u00edncipe mestizo\u2122 en concierto"},"content":{"rendered":"<div class=\"buy-tickets\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-lg-12\">\n                <div class=\"slideshow__controls justify-content-start\">\n                    <button class=\"controls__prev ticket-controls__prev\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                            <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                        <\/svg>\n                    <\/button>\n                    <button class=\"controls__next ticket-controls__next\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                            <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                        <\/svg>\n                    <\/button>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"row\">\n            <div class=\"col-lg-12\">\n                <div class=\"ticket-slideshow\">\n                    <div class=\"single-ticket\">\n    <p>viernes<br>\n        4 de septiembre de 2026        <br>\n        7:30pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n    <\/div>\n<div class=\"single-ticket\">\n    <p>s\u00e1bado<br>\n        5 de septiembre de 2026        <br>\n        7:30pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n    <\/div>\n<div class=\"single-ticket\">\n    <p>domingo<br>\n        6 de septiembre de 2026        <br>\n        2:00pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"richtext m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-10\">\n\t\t\t\t\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-173bac1297f3731843f76166b33e73d5\" style=\"background-color:#1c3172\">Las entradas estar\u00e1n disponibles para su compra en <strong>7 de julio<\/strong>, \u00a1pero como suscriptor puedes obtener acceso anticipado! Al suscribirte, obtienes asientos preferentes en cada concierto, ahorras hasta 20% del precio actual de la entrada, disfrutas de cambios de entradas gratuitos y acceso anticipado a los conciertos reci\u00e9n anunciados. <a href=\"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/subscriptions-and-packages\/\" data-type=\"page\" data-id=\"16675\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p>Revive la magia del sexto a\u00f1o en&nbsp;<em>Harry Potter y el pr\u00edncipe mestizo\u2122 en concierto.<\/em>&nbsp;Con esta pel\u00edcula, basada en la sexta entrega de la saga cl\u00e1sica, los fans de todas las edades pueden ahora disfrutar de la emocionante historia de la obsesi\u00f3n de Harry por un misterioso libro de pociones, acompa\u00f1ados por la m\u00fasica de una orquesta sinf\u00f3nica en directo, mientras Harry surca la gran pantalla en alta definici\u00f3n.<\/p>\n\n\n\n<p>La saga contin\u00faa mientras Harry se eleva en la gran pantalla en alta definici\u00f3n en&nbsp;<em>Harry Potter y el pr\u00edncipe mestizo\u2122 en concierto.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\">Todos los personajes y elementos \u00a9 &amp; \u2122 Warner Bros. Entertainment Inc. Derechos de publicaci\u00f3n \u00a9 JKR.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-80853343e3d79f15733d85723efa6f95\" style=\"background-color:#1c3172\"><strong>C\u00f3mo llegar al Meyerson<\/strong><br>El Meyerson abre dos horas antes de cada concierto. Le recomendamos llegar al menos 30 minutos antes para estacionarse y encontrar su asiento. \u00a1Visite nuestra p\u00e1gina de C\u00f3mo llegar y estacionamiento para obtener m\u00e1s detalles! <a href=\"https:\/\/www.dallassymphony.org\/es\/plan-your-visit\/directions-parking\/\" data-type=\"page\" data-id=\"561\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-3f6d539f5f0501f14659c262d0be8836\" style=\"background-color:#1c3172\"><strong>Su visita<\/strong><br>Una vez en el Meyerson, visite la tienda Symphony Shop patrocinada por Capital One o tome un refrigerio y una bebida en el vest\u00edbulo. En la sala de conciertos no se permite tomar fotos con flash ni grabar videos. \u00a1Se pueden consumir las bebidas compradas en el recinto! <a href=\"https:\/\/www.dallassymphony.org\/es\/plan-your-visit\/\" data-type=\"page\" data-id=\"559\">Aprende m\u00e1s<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-5d1cfff5f551c046874e4eaa20c042ac\" style=\"background-color:#1c3172\"><strong>\u00bfTienes 10 o m\u00e1s personas?<\/strong><br>\u00bfEst\u00e1s planeando una salida nocturna o buscas una forma \u00fanica de celebrar algo? Con m\u00fasica de talla mundial, ventajas exclusivas para grupos y descuentos, una noche en la DSO es perfecta para crear recuerdos inolvidables. <a href=\"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/group-sales\/\" data-type=\"page\" data-id=\"550\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-249b2a0e9110255d9146ebbab5a15e11\" style=\"background-color:#1c3172\"><strong>Combina y ahorra<\/strong><br>\u00a1Organiza tu propia temporada personalizada de conciertos inolvidables! \u00a1Consigue hasta 20% de ahorro, disfruta de cambios de boletos gratuitos y accede antes que nadie a los conciertos reci\u00e9n anunciados simplemente combinando 3 o m\u00e1s conciertos! <a href=\"https:\/\/www.dallassymphony.org\/es\/ticket-packages\/\" data-type=\"page\" data-id=\"17376\">Aprende m\u00e1s<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n    <div class=\"featured-concerts grad-to-left m-spacer\">\n        <div class=\"container-fluid\">\n            <div class=\"row\">\n                <div class=\"col-md-7 col-7 offset-md-1\">\n                    <h1 class=\"serif__elight-58-italic\">Tambi\u00e9n le puede interesar <\/h1>\n                <\/div>\n                <div class=\"col-md-4 col-5\">\n                    <div class=\"controls__wrapper\">\n                        <div class=\"slideshow__controls d-none d-lg-block\">\n                            <button class=\"controls__prev\"  data-button-id=\"bf6f82eddc3085029e5cdfa5cc9774fe\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                    <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                                <\/svg>\n                            <\/button>\n                            <button class=\"controls__next\" data-button-id=\"bf6f82eddc3085029e5cdfa5cc9774fe\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                    <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                                <\/svg>\n                            <\/button>\n                        <\/div>\n\n\t                                        <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-md-11 offset-md-1\">\n                    <div class=\"slideshow\">\n                        <div class=\"dso__slides\" data-button-id=\"bf6f82eddc3085029e5cdfa5cc9774fe\">\n                            <div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/disneys-hocus-pocus-in-concert-live-to-film\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Hocus-Pocus_1600x900-1.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Hocus Pocus de Disney en concierto en vivo y en directo            <\/h4>\n            <p class=\"serif__light-16-italic\">9-11 de octubre de 2026<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n<div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/holidays-with-the-dso-subs-2026\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_HOL02-Holidays-with-the-DSO.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Vacaciones con la DSO            <\/h4>\n            <p class=\"serif__light-16-italic\">11-13 de diciembre de 2026<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n<div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/disney-and-pixars-up-in-concert\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/Up_1600x900.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                UP en concierto, de Disney y Pixar            <\/h4>\n            <p class=\"serif__light-16-italic\">26-28 de febrero de 2027<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-11 offset-1\">\n                    <div class=\"slideshow__controls d-lg-none\">\n                        <button class=\"controls__prev\" data-prev=\"#\" data-button-id=\"bf6f82eddc3085029e5cdfa5cc9774fe\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                            <\/svg>\n                        <\/button>\n                        <button class=\"controls__next\" data-next=\"#\" data-button-id=\"bf6f82eddc3085029e5cdfa5cc9774fe\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                            <\/svg>\n                        <\/button>\n                    <\/div>\n\n                <\/div>\n\n            <\/div>\n        <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>Revive la magia del sexto a\u00f1o mientras Harry se eleva en la gran pantalla en alta definici\u00f3n en Harry Potter y el Pr\u00edncipe Mestizo\u2122 en concierto.<\/p>","protected":false},"featured_media":30352,"template":"","dso_concert_series":[63,38],"class_list":["post-29999","dso_prod_season","type-dso_prod_season","status-publish","has-post-thumbnail","hentry","dso_concert_series-dallas-symphony-presents","dso_concert_series-movies"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/29999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season"}],"about":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/types\/dso_prod_season"}],"version-history":[{"count":0,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/29999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media\/30352"}],"wp:attachment":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media?parent=29999"}],"wp:term":[{"taxonomy":"dso_concert_series","embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_concert_series?post=29999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}