{"id":29989,"date":"2026-02-26T10:00:00","date_gmt":"2026-02-26T16:00:00","guid":{"rendered":"https:\/\/www.dallassymphony.org\/?post_type=dso_prod_season&#038;p=29989"},"modified":"2026-07-07T09:16:46","modified_gmt":"2026-07-07T14:16:46","slug":"billy-joel","status":"publish","type":"dso_prod_season","link":"https:\/\/www.dallassymphony.org\/es\/productions\/billy-joel\/","title":{"rendered":"La m\u00fasica de Billy Joel"},"content":{"rendered":"<div class=\"buy-tickets\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-lg-12\">\n                <div class=\"slideshow__controls justify-content-start\">\n                    <button class=\"controls__prev ticket-controls__prev\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                            <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                        <\/svg>\n                    <\/button>\n                    <button class=\"controls__next ticket-controls__next\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                            <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                        <\/svg>\n                    <\/button>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"row\">\n            <div class=\"col-lg-12\">\n                <div class=\"ticket-slideshow\">\n                    <div class=\"single-ticket\">\n    <p>viernes<br>\n        21 de mayo de 2027        <br>\n        7:30pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n        <a href=\"https:\/\/secure.dallassymphony.org\/16145\/16231\">\n\t\t<span class=\"a-hover\">Compra de entradas<\/span>\n\t<\/a>\n    <p class=\"buy-tickets__starting-at\">Entradas a partir de $38<\/p>\n    <\/div>\n<div class=\"single-ticket\">\n    <p>s\u00e1bado<br>\n        22 de mayo de 2027        <br>\n        7:30pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n        <a href=\"https:\/\/secure.dallassymphony.org\/16145\/16233\">\n\t\t<span class=\"a-hover\">Compra de entradas<\/span>\n\t<\/a>\n    <p class=\"buy-tickets__starting-at\">Entradas a partir de $38<\/p>\n    <\/div>\n<div class=\"single-ticket\">\n    <p>domingo<br>\n        23 de mayo de 2027        <br>\n        2:00pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n        <a href=\"https:\/\/secure.dallassymphony.org\/16145\/16234\">\n\t\t<span class=\"a-hover\">Compra de entradas<\/span>\n\t<\/a>\n    <p class=\"buy-tickets__starting-at\">Entradas a partir de $38<\/p>\n    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"richtext m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-10\">\n\t\t\t\t\n\n<p><strong>\u00a1Acomp\u00e1\u00f1enos en esta nueva versi\u00f3n del emblem\u00e1tico repertorio de Billy Joel, que incluye \u201cOnly the Good Die Young\u201d, \u201cJust the Way You Are\u201d, \u201cPiano Man\u201d, \u201cNew York State of Mind\u201d y muchas m\u00e1s!<\/strong><\/p>\n\n\n\n<p><strong>Enrico L\u00f3pez-Y\u00e1\u00f1ez&nbsp;<\/strong>Conduce<br><strong>Tony DeSare&nbsp;<\/strong>Voz y piano&nbsp;<br><strong>Michael Klopp<\/strong>&nbsp;Bater\u00eda&nbsp;<br><strong>Dylan Shamat&nbsp;<\/strong>Bass&nbsp;<\/p>\n\n\n\n<p>El primer \u00e1lbum que el aclamado vocalista y pianista Tony DeSare compr\u00f3 con su propio dinero fue el de Billy Joel.&nbsp;<em>Frente de tormenta<\/em>. D\u00e9cadas m\u00e1s tarde, DeSare une fuerzas con la Orquesta Sinf\u00f3nica de Dallas para rendir un apasionado homenaje al mism\u00edsimo Piano Man. La alegr\u00eda contagiosa, la iron\u00eda juguetona y la s\u00f3lida musicalidad de DeSare transmiten el ingenio y la calidez que hicieron de las canciones de Billy Joel cl\u00e1sicos atemporales. Con temas favoritos como \u201cOnly the Good Die Young\u201d, \u201cJust the Way You Are\u201d, \u201cPiano Man\u201d, \u201cNew York State of Mind\u201d y muchos m\u00e1s, \u00fanase a la DSO en este viaje a trav\u00e9s de la m\u00fasica, las historias y el legado de Billy Joel.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-80853343e3d79f15733d85723efa6f95\" style=\"background-color:#1c3172\"><strong>C\u00f3mo llegar al Meyerson<\/strong><br>El Meyerson abre dos horas antes de cada concierto. Le recomendamos llegar al menos 30 minutos antes para estacionarse y encontrar su asiento. \u00a1Visite nuestra p\u00e1gina de C\u00f3mo llegar y estacionamiento para obtener m\u00e1s detalles! <a href=\"https:\/\/www.dallassymphony.org\/es\/plan-your-visit\/directions-parking\/\" data-type=\"page\" data-id=\"561\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-3f6d539f5f0501f14659c262d0be8836\" style=\"background-color:#1c3172\"><strong>Su visita<\/strong><br>Una vez en el Meyerson, visite la tienda Symphony Shop patrocinada por Capital One o tome un refrigerio y una bebida en el vest\u00edbulo. En la sala de conciertos no se permite tomar fotos con flash ni grabar videos. \u00a1Se pueden consumir las bebidas compradas en el recinto! <a href=\"https:\/\/www.dallassymphony.org\/es\/plan-your-visit\/\" data-type=\"page\" data-id=\"559\">Aprende m\u00e1s<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-5d1cfff5f551c046874e4eaa20c042ac\" style=\"background-color:#1c3172\"><strong>\u00bfTienes 10 o m\u00e1s personas?<\/strong><br>\u00bfEst\u00e1s planeando una salida nocturna o buscas una forma \u00fanica de celebrar algo? Con m\u00fasica de talla mundial, ventajas exclusivas para grupos y descuentos, una noche en la DSO es perfecta para crear recuerdos inolvidables. <a href=\"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/group-sales\/\" data-type=\"page\" data-id=\"550\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-249b2a0e9110255d9146ebbab5a15e11\" style=\"background-color:#1c3172\"><strong>Combina y ahorra<\/strong><br>\u00a1Organiza tu propia temporada personalizada de conciertos inolvidables! \u00a1Consigue hasta 20% de ahorro, disfruta de cambios de boletos gratuitos y accede antes que nadie a los conciertos reci\u00e9n anunciados simplemente combinando 3 o m\u00e1s conciertos! <a href=\"https:\/\/www.dallassymphony.org\/es\/ticket-packages\/\" data-type=\"page\" data-id=\"17376\">Aprende m\u00e1s<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"has-medium-font-size\"><strong>La serie DSO Pops cuenta con el generoso patrocinio de<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"115\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/03\/Capital-One-Logo-Black-300-px.png\" alt=\"\" class=\"wp-image-25792\" style=\"width:264px;height:auto\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/03\/Capital-One-Logo-Black-300-px.png 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/03\/Capital-One-Logo-Black-300-px-18x7.png 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-default\"\/>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"richtext m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-10\">\n\t\t\t\t\n<div class=\"edp-musician-grid m-spacer grad-to-right\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<h1>Con la presentaci\u00f3n de<\/h1>\n\t\t\t\t<h2><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-lg-6\">\n\t<div class=\"edp__musician-card\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"262\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-262x262.png\" class=\"attachment-262x262 size-262x262 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-262x262.png 262w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-300x300.png 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-1024x1024.png 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-150x150.png 150w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-768x768.png 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-12x12.png 12w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-350x350.png 350w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited-445x445.png 445w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/04\/Enrico-Lopez-Yanez-Crop-Canva-edited.png 1080w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/>\t\t<div class=\"content__wrapper\">\n\t\t\t<h4>Enrico L\u00f3pez-Y\u00e1\u00f1ez<\/h4>\n\n\t\t\t<p>Director principal, Dallas Symphony Presents<\/p>\n<p>C\u00e1tedra Nancy A. Nasher y David J. Haemisegger<\/p>\n\n                            <a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/people\/enrico-lopez-yanez\/\">Leer m\u00e1s<\/a>\n            \t\t<\/div>\n\t<\/div>\n<\/div><div class=\"col-lg-6\">\n\t<div class=\"edp__musician-card\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"262\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-262x262.png\" class=\"attachment-262x262 size-262x262 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-262x262.png 262w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-300x300.png 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-150x150.png 150w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-768x768.png 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-12x12.png 12w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-350x350.png 350w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1-445x445.png 445w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2021\/03\/Tony-DeSare-1000x1000-1.png 1000w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/>\t\t<div class=\"content__wrapper\">\n\t\t\t<h4>Tony DeSare<\/h4>\n\n\t\t\t<p>Vocalista<\/p>\n\n                            <a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/people\/tony-desare\/\">Leer m\u00e1s<\/a>\n            \t\t<\/div>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n    <div class=\"featured-concerts grad-to-left m-spacer\">\n        <div class=\"container-fluid\">\n            <div class=\"row\">\n                <div class=\"col-md-7 col-7 offset-md-1\">\n                    <h1 class=\"serif__elight-58-italic\">Tambi\u00e9n le puede interesar <\/h1>\n                <\/div>\n                <div class=\"col-md-4 col-5\">\n                    <div class=\"controls__wrapper\">\n                        <div class=\"slideshow__controls d-none d-lg-block\">\n                            <button class=\"controls__prev\"  data-button-id=\"f2b431c92354a40cbf44c28dc74a71b6\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                    <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                                <\/svg>\n                            <\/button>\n                            <button class=\"controls__next\" data-button-id=\"f2b431c92354a40cbf44c28dc74a71b6\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                    <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                                <\/svg>\n                            <\/button>\n                        <\/div>\n\n\t                                        <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-md-11 offset-md-1\">\n                    <div class=\"slideshow\">\n                        <div class=\"dso__slides\" data-button-id=\"f2b431c92354a40cbf44c28dc74a71b6\">\n                            <div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/ellington-strayhorn-gershwin\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS03-Ellington-Strayhorn-Gershwin.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Ellington, Strayhorn y Gershwin            <\/h4>\n            <p class=\"serif__light-16-italic\">6-8 de noviembre de 2026<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n<div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/rock-legends\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS05-Laurel-Canyon-1.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Leyendas del rock de los a\u00f1os 60 y 70: Sonidos de Laurel Canyon            <\/h4>\n            <p class=\"serif__light-16-italic\">29-30 de enero de 2027<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n<div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/summer-breeze\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/25-26-Web-1600x900_POPS07-Summer-Breeze.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Brisa de verano: Cl\u00e1sicos del yacht rock            <\/h4>\n            <p class=\"serif__light-16-italic\">16 y 17 de abril de 2027<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-11 offset-1\">\n                    <div class=\"slideshow__controls d-lg-none\">\n                        <button class=\"controls__prev\" data-prev=\"#\" data-button-id=\"f2b431c92354a40cbf44c28dc74a71b6\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                            <\/svg>\n                        <\/button>\n                        <button class=\"controls__next\" data-next=\"#\" data-button-id=\"f2b431c92354a40cbf44c28dc74a71b6\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                            <\/svg>\n                        <\/button>\n                    <\/div>\n\n                <\/div>\n\n            <\/div>\n        <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a1Acomp\u00e1\u00f1enos en esta nueva versi\u00f3n del emblem\u00e1tico repertorio de Billy Joel, que incluye \u201cOnly the Good Die Young\u201d, \u201cJust the Way You Are\u201d, \u201cPiano Man\u201d, \u201cNew York State of Mind\u201d y muchas m\u00e1s!<\/p>","protected":false},"featured_media":30249,"template":"","dso_concert_series":[32],"class_list":["post-29989","dso_prod_season","type-dso_prod_season","status-publish","has-post-thumbnail","hentry","dso_concert_series-pops"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/29989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season"}],"about":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/types\/dso_prod_season"}],"version-history":[{"count":1,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/29989\/revisions"}],"predecessor-version":[{"id":31930,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/29989\/revisions\/31930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media\/30249"}],"wp:attachment":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media?parent=29989"}],"wp:term":[{"taxonomy":"dso_concert_series","embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_concert_series?post=29989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}