{"id":29946,"date":"2026-02-26T09:57:00","date_gmt":"2026-02-26T15:57:00","guid":{"rendered":"https:\/\/www.dallassymphony.org\/?post_type=dso_prod_season&#038;p=29946"},"modified":"2026-03-06T18:50:19","modified_gmt":"2026-03-07T00:50:19","slug":"schumann-brahms","status":"publish","type":"dso_prod_season","link":"https:\/\/www.dallassymphony.org\/es\/productions\/schumann-brahms\/","title":{"rendered":"Schumann y Brahms con Randall Goosby"},"content":{"rendered":"<div class=\"buy-tickets\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-lg-12\">\n                <div class=\"slideshow__controls justify-content-start\">\n                    <button class=\"controls__prev ticket-controls__prev\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                            <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                        <\/svg>\n                    <\/button>\n                    <button class=\"controls__next ticket-controls__next\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                            <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                        <\/svg>\n                    <\/button>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"row\">\n            <div class=\"col-lg-12\">\n                <div class=\"ticket-slideshow\">\n                    <div class=\"single-ticket\">\n    <p>viernes<br>\n        22 de enero de 2027        <br>\n        7:30pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n    <\/div>\n<div class=\"single-ticket\">\n    <p>s\u00e1bado<br>\n        23 de enero de 2027        <br>\n        7:30pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n    <\/div>\n<div class=\"single-ticket\">\n    <p>domingo<br>\n        24 de enero de 2027        <br>\n        2:00pm<\/p>\n\n    <p class=\"optional-msg\">\n            <\/p>\n    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"richtext m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-10\">\n\t\t\t\t\n\n<p><strong>El violinista Randall Goosby transmite la poes\u00eda et\u00e9rea de Brahms en su regreso a la DSO, y Schumann rinde homenaje a la belleza floreciente de la primavera.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-173bac1297f3731843f76166b33e73d5\" style=\"background-color:#1c3172\">Las entradas estar\u00e1n disponibles para su compra en <strong>7 de julio<\/strong>, \u00a1pero como suscriptor puedes obtener acceso anticipado! Al suscribirte, obtienes asientos preferentes en cada concierto, ahorras hasta 20% del precio actual de la entrada, disfrutas de cambios de entradas gratuitos y acceso anticipado a los conciertos reci\u00e9n anunciados. <a href=\"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/subscriptions-and-packages\/\" data-type=\"page\" data-id=\"16675\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p><strong>Matthias Pintscher<\/strong> Conduce<br><strong>Randall Goosby<\/strong> Viol\u00edn<\/p>\n\n\n\n<p><strong>SCHUMANN<\/strong> Sinfon\u00eda n.\u00ba 1 en si bemol mayor, \u201cPrimavera\u201d<br><strong>BRAHMS<\/strong> Concierto para viol\u00edn en re mayor<\/p>\n\n\n\n<p>Puede que Brahms tardara 25 a\u00f1os en componer un concierto para viol\u00edn para su buen amigo Joseph Joachim, pero la espera mereci\u00f3 la pena. Desde momentos de poes\u00eda et\u00e9rea hasta el apasionado final inspirado en la m\u00fasica de baile h\u00fangara, el Concierto para viol\u00edn de Brahms libera todo el potencial expresivo del instrumento, convirti\u00e9ndolo en el veh\u00edculo perfecto para el \u2019calor, elegancia y potencia\u201c del violinista Randall Goosby (<em>Am\u00e9rica musical<\/em>).&nbsp;<\/p>\n\n\n\n<p>\u201cPor muy mayor que se sea\u201d, escribi\u00f3 Schumann, \u201ccada a\u00f1o vuelve el anhelo por la primavera\u201d. Mientras el invierno sigue reinando fuera, d\u00e9jese llevar por los v\u00edvidos sue\u00f1os primaverales con la Sinfon\u00eda n.\u00ba 1 de Schumann. Evocando el florecimiento de la estaci\u00f3n con radiantes fanfarrias de metales y sensuales serenatas, Schumann rinde homenaje a la impresionante belleza de la naturaleza y a su milagroso ciclo de renovaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-fcc05c629ba4e2118425782148b8f16a\" style=\"background-color:#1c3172\"><strong>Preludios de actuaci\u00f3n<\/strong><br>\u00a1Acomp\u00e1\u00f1enos en una charla previa al concierto, \u00fanica y en profundidad, con la directora asistente Shira Samuels-Shragg! Las charlas tendr\u00e1n lugar en el Horchow Hall a partir de las 6:30 p. m. cada noche de concierto y a la 1:00 p. m. el domingo. <a href=\"https:\/\/www.dallassymphony.org\/es\/community-education\/dso-music-programs\/adult-programs\/\" data-type=\"page\" data-id=\"5221\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-80853343e3d79f15733d85723efa6f95\" style=\"background-color:#1c3172\"><strong>C\u00f3mo llegar al Meyerson<\/strong><br>El Meyerson abre dos horas antes de cada concierto. Le recomendamos llegar al menos 30 minutos antes para estacionarse y encontrar su asiento. \u00a1Visite nuestra p\u00e1gina de C\u00f3mo llegar y estacionamiento para obtener m\u00e1s detalles! <a href=\"https:\/\/www.dallassymphony.org\/es\/plan-your-visit\/directions-parking\/\" data-type=\"page\" data-id=\"561\">Aprende m\u00e1s<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-249b2a0e9110255d9146ebbab5a15e11\" style=\"background-color:#1c3172\"><strong>Combina y ahorra<\/strong><br>\u00a1Organiza tu propia temporada personalizada de conciertos inolvidables! \u00a1Consigue hasta 20% de ahorro, disfruta de cambios de boletos gratuitos y accede antes que nadie a los conciertos reci\u00e9n anunciados simplemente combinando 3 o m\u00e1s conciertos! <a href=\"https:\/\/www.dallassymphony.org\/es\/ticket-packages\/\" data-type=\"page\" data-id=\"17376\">Aprende m\u00e1s<\/a><\/p>\n\n\n\n<p class=\"cta-content-highlight cta__text-overlay has-white-color has-text-color has-background has-link-color wp-elements-5d1cfff5f551c046874e4eaa20c042ac\" style=\"background-color:#1c3172\"><strong>\u00bfTienes 10 o m\u00e1s personas?<\/strong><br>\u00bfEst\u00e1s planeando una salida nocturna o buscas una forma \u00fanica de celebrar algo? Con m\u00fasica de talla mundial, ventajas exclusivas para grupos y descuentos, una noche en la DSO es perfecta para crear recuerdos inolvidables. <a href=\"https:\/\/www.dallassymphony.org\/es\/concerts-and-events\/group-sales\/\" data-type=\"page\" data-id=\"550\">Aprende m\u00e1s<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"has-medium-font-size\"><strong>La serie cl\u00e1sica de la DSO cuenta con el generoso patrocinio de<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1523\" height=\"242\" src=\"https:\/\/dallassymp2stg.wpenginepowered.com\/wp-content\/uploads\/2025\/10\/TI.OneLine.Color_.png\" alt=\"\" class=\"wp-image-28868\" style=\"width:300px\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/10\/TI.OneLine.Color_.png 1523w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/10\/TI.OneLine.Color_-300x48.png 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/10\/TI.OneLine.Color_-1024x163.png 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/10\/TI.OneLine.Color_-768x122.png 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2025\/10\/TI.OneLine.Color_-18x3.png 18w\" sizes=\"auto, (max-width: 1523px) 100vw, 1523px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-default\"\/>\n\n\n<div class=\"edp-musician-grid m-spacer grad-to-right\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<h1>Con la presentaci\u00f3n de<\/h1>\n\t\t\t\t<h2><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-lg-6\">\n\t<div class=\"edp__musician-card\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"262\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-262x262.png\" class=\"attachment-262x262 size-262x262 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-262x262.png 262w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-300x300.png 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-1024x1024.png 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-150x150.png 150w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-768x768.png 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-12x12.png 12w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-350x350.png 350w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby-445x445.png 445w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/02\/Randall-Goosby.png 1200w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/>\t\t<div class=\"content__wrapper\">\n\t\t\t<h4>Randall Goosby<\/h4>\n\n\t\t\t<p>Viol\u00edn<\/p>\n\n                            <a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/people\/randall-goosby\/\">Leer m\u00e1s<\/a>\n            \t\t<\/div>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n    <div class=\"featured-concerts grad-to-left m-spacer\">\n        <div class=\"container-fluid\">\n            <div class=\"row\">\n                <div class=\"col-md-7 col-7 offset-md-1\">\n                    <h1 class=\"serif__elight-58-italic\">Tambi\u00e9n le puede interesar <\/h1>\n                <\/div>\n                <div class=\"col-md-4 col-5\">\n                    <div class=\"controls__wrapper\">\n                        <div class=\"slideshow__controls d-none d-lg-block\">\n                            <button class=\"controls__prev\"  data-button-id=\"16fa380e86426815b632e5cdc66611dc\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                    <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                                <\/svg>\n                            <\/button>\n                            <button class=\"controls__next\" data-button-id=\"16fa380e86426815b632e5cdc66611dc\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                    <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                                <\/svg>\n                            <\/button>\n                        <\/div>\n\n\t                                        <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-md-11 offset-md-1\">\n                    <div class=\"slideshow\">\n                        <div class=\"dso__slides\" data-button-id=\"16fa380e86426815b632e5cdc66611dc\">\n                            <div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/tchaikovskys-piano-concerto\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA07_Tchaikovskys-Piano-Concerto-No.1-and-Swan-Lake.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Concierto para piano n.\u00ba 1 y El lago de los cisnes, de Tchaikovsky            <\/h4>\n            <p class=\"serif__light-16-italic\">27-29 de noviembre de 2026<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n<div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/brahms-mozart\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA08_Brahms-and-Mozart-with-David-Buck-and-Emily-Levin.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Brahms y Mozart con David Buck y Emily Levin            <\/h4>\n            <p class=\"serif__light-16-italic\">14-15 de enero de 2027<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n<div class=\"concert__card\" style=\"margin-right: 15px\">\n    <a href=\"https:\/\/www.dallassymphony.org\/es\/productions\/mendelssohn-beethoven\/\">\n        <div class=\"img__wrapper\">\n\t        <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"218\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-388x218.jpg\" class=\"attachment-388x218 size-388x218 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-388x218.jpg 388w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-300x169.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-1024x576.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-768x432.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-1536x864.jpg 1536w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-18x10.jpg 18w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-540x303.jpg 540w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-666x375.jpg 666w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr-735x413.jpg 735w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2026\/02\/CLA17_Mendelssohn-and-Beethoven-with-Alexander-Kerr.jpg 1600w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/>        <\/div>\n        <div class=\"content__wrapper\">\n            <h4 class=\"serif__light-22\">\n                Mendelssohn y Beethoven con Alexander Kerr            <\/h4>\n            <p class=\"serif__light-16-italic\">22-24 de abril de 2027<\/p>\n            <p class=\"sans-cond__med-14\">M\u00e1s informaci\u00f3n y compra de entradas<\/p>\n        <\/div>\n    <\/a>\n<\/div>\n\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"row\">\n                <div class=\"col-11 offset-1\">\n                    <div class=\"slideshow__controls d-lg-none\">\n                        <button class=\"controls__prev\" data-prev=\"#\" data-button-id=\"16fa380e86426815b632e5cdc66611dc\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                            <\/svg>\n                        <\/button>\n                        <button class=\"controls__next\" data-next=\"#\" data-button-id=\"16fa380e86426815b632e5cdc66611dc\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" enable-background=\"new 0 0 24 24\" height=\"24\" viewbox=\"0 0 24 24\" width=\"24\">\n                                <g><rect fill=\"none\" height=\"24\" width=\"24\"\/><path d=\"M12,4c4.41,0,8,3.59,8,8s-3.59,8-8,8s-8-3.59-8-8S7.59,4,12,4 M12,2C6.48,2,2,6.48,2,12c0,5.52,4.48,10,10,10 c5.52,0,10-4.48,10-10C22,6.48,17.52,2,12,2L12,2z M13,12l0-4h-2l0,4H8l4,4l4-4H13z\"\/><\/g>\n                            <\/svg>\n                        <\/button>\n                    <\/div>\n\n                <\/div>\n\n            <\/div>\n        <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>El violinista Randall Goosby transmite la poes\u00eda et\u00e9rea de Brahms en su regreso a la DSO, y Schumann rinde homenaje a la belleza floreciente de la primavera.<\/p>","protected":false},"featured_media":30511,"template":"","dso_concert_series":[31],"class_list":["post-29946","dso_prod_season","type-dso_prod_season","status-publish","has-post-thumbnail","hentry","dso_concert_series-classical"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/29946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season"}],"about":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/types\/dso_prod_season"}],"version-history":[{"count":0,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/29946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media\/30511"}],"wp:attachment":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media?parent=29946"}],"wp:term":[{"taxonomy":"dso_concert_series","embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_concert_series?post=29946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}