{"id":10366,"date":"2022-12-15T14:03:53","date_gmt":"2022-12-15T20:03:53","guid":{"rendered":"https:\/\/www.dallassymphony.org\/?post_type=dso_prod_season&#038;p=10366"},"modified":"2023-03-03T17:09:33","modified_gmt":"2023-03-03T23:09:33","slug":"the-music-of-drake-x-tchaikovsky-composed-by-steve-hackman","status":"publish","type":"dso_prod_season","link":"https:\/\/www.dallassymphony.org\/es\/productions\/the-music-of-drake-x-tchaikovsky-composed-by-steve-hackman\/","title":{"rendered":"La m\u00fasica de Tchaikovsky X Drake Compuesta por Steve Hackman"},"content":{"rendered":"<div class=\"richtext m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-10\">\n\t\t\t\t\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background\" style=\"background-color:#e5e5e5;color:#e5e5e5\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6:30 <\/strong>C\u00f3ctel de recepci\u00f3n<strong> - 8:00 <\/strong>Concierto<strong> - 9:30 <\/strong>Despu\u00e9s de la fiesta<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background\" style=\"background-color:#e5e5e5;color:#e5e5e5\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\"><strong>STEVE HACKMAN<\/strong> lleva a cabo<br><strong>MALIA CIVETZ<\/strong> solista<br><strong>INDIA CARNEY<\/strong> solista<br><strong>MARIO JOSE<\/strong> solista<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\"><strong>JECOREY ARTHUR<\/strong> rapero<br><strong>TARON LOCKETT<\/strong> bater\u00eda<br><strong>BRAYLON LACY<\/strong> bajista<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Llamamiento a todos los j\u00f3venes profesionales: \u00danase a la DSO en una exclusiva velada de m\u00fasica, c\u00f3cteles y aperitivos a beneficio del Programa de J\u00f3venes M\u00fasicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tchaikovsky<em>&nbsp;<\/em>X Drake es una s\u00edntesis sinf\u00f3nica que mezcla la m\u00fasica de dos compositores-rom\u00e1nticos separados por casi un siglo. Quince canciones de Drake se entretejen en la \u00e9pica de Chaikovski&nbsp;<em>Quinta Sinfon\u00eda<\/em>&nbsp;de todas las formas imaginables.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Adem\u00e1s de las localidades para el concierto, las entradas incluyen un c\u00f3ctel especial de cortes\u00eda, acceso al c\u00f3ctel previo al concierto y a la fiesta posterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las entradas VIP, que s\u00f3lo est\u00e1n disponibles para los palcos de nivel Loge, tambi\u00e9n incluyen una experiencia gastron\u00f3mica superior, con bebidas gratuitas adicionales, y acceso reservado a la After-Party Lounge.<\/p>\n<\/blockquote>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-please-note-this-concert-will-feature-the-music-of-drake-performed-by-the-dallas-symphony-orchestra-the-artist-drake-will-not-be-in-attendance\"><em>Nota: Este concierto presentar\u00e1 la m\u00fasica de Drake interpretada por la Orquesta Sinf\u00f3nica de Dallas. El artista Drake no estar\u00e1 presente.&nbsp;<\/em><\/h6>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>MORTON H. CENTRO SINF\u00d3NICO MEYERSON<\/strong><br>Calle Flora 2301<br>Dallas, TX 75201<\/p>\n<\/blockquote>\n\n\n<div class=\"container\">\n    <div class=\"row\">\n        <div class=\"col-10\">\n            <div class=\"share d-flex align-items-center\">\n                <p class=\"mb-0 serif__light-16\">COMPARTIR<\/p><div data-network=\"facebook\" class=\"st-custom-button facebook\" data-title=\"&quot;The\" music of tchaikovsky x drake composed by steve hackman&quot; data-description=\"&quot;Calling\" all young professionals: join the dso for an exclusive evening music, cocktails, and light bites benefiting musicians program.&quot; data-message =\"&quot;Calling\" program.\r\n\r\nhttps:>Facebook<span class=\"count\"><\/span><\/div>            <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"edp-musician-grid m-spacer grad-to-right\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12\">\n\t\t\t\t<h1><\/h1>\n\t\t\t\t<h2><\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-lg-6\">\n\t<div class=\"edp__musician-card\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"262\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-262x262.png\" class=\"attachment-262x262 size-262x262 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-262x262.png 262w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-300x300.png 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-1024x1024.png 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-150x150.png 150w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-768x768.png 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-12x12.png 12w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-350x350.png 350w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2-445x445.png 445w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/12\/Steve-Hackman-2.png 1200w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/>\t\t<div class=\"content__wrapper\">\n\t\t\t<h4>Steve Hackman<\/h4>\n\n\t\t\t<p>Compositor\/Conductor\/Productor<\/p>\n\n                            <a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/people\/steve-hackman\/\">Leer m\u00e1s<\/a>\n            \t\t<\/div>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"richtext m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-10\">\n\t\t\t\t\n\n<div style=\"height:0px\" aria-hidden=\"true\" id=\"program\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\">Libro del programa<\/h1>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n\n<div style=\"position:relative;padding-top:max(60%,326px);height:0;width:100%\"><iframe allow=\"clipboard-write\" sandbox=\"allow-top-navigation allow-top-navigation-by-user-activation allow-downloads allow-scripts allow-same-origin allow-popups allow-modals allow-popups-to-escape-sandbox allow-forms\" allowfullscreen=\"true\" style=\"position:absolute;border:none;width:100%;height:100%;left:0;right:0;top:0;bottom:0;\" src=\"https:\/\/e.issuu.com\/embed.html?d=tchaikovsky_x_drake_program_book&amp;hideIssuuLogo=true&amp;hideShareButton=true&amp;u=dalsym\"><\/iframe><\/div>","protected":false},"excerpt":{"rendered":"<p>Llamamiento a todos los j\u00f3venes profesionales: \u00danase a la DSO en una exclusiva velada de m\u00fasica, c\u00f3cteles y aperitivos a beneficio del Programa de J\u00f3venes M\u00fasicos.<\/p>","protected":false},"featured_media":10368,"template":"","dso_concert_series":[],"class_list":["post-10366","dso_prod_season","type-dso_prod_season","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/10366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season"}],"about":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/types\/dso_prod_season"}],"version-history":[{"count":0,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_prod_season\/10366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media\/10368"}],"wp:attachment":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media?parent=10366"}],"wp:term":[{"taxonomy":"dso_concert_series","embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_concert_series?post=10366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}