{"id":8990,"date":"2022-05-12T14:52:46","date_gmt":"2022-05-12T19:52:46","guid":{"rendered":"https:\/\/www.dallassymphony.org\/?post_type=dso_person&#038;p=8990"},"modified":"2023-07-20T11:34:57","modified_gmt":"2023-07-20T16:34:57","slug":"andy-pham","status":"publish","type":"dso_person","link":"https:\/\/www.dallassymphony.org\/es\/people\/andy-pham\/","title":{"rendered":"Andy Pham"},"content":{"rendered":"<div class=\"hero__no-img bg-blue-8\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-10\">\n\n\t\t\t\t<ul class=\"breadcrumbs\">\n    \t<li class=\"breadcrumb__link\">\n\t\t<a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/\">Inicio<\/a>\n\t<\/li>\n    \t<li class=\"breadcrumb__link a-styles\">\n\t\t<a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/about-the-dso\/\">Sobre el DSO<\/a>\n\t<\/li>\n    \t<li class=\"breadcrumb__link a-styles\">\n\t\t<a class=\"a-hover\" href=\"https:\/\/www.dallassymphony.org\/es\/about-the-dso\/people\/\">Gente<\/a>\n\t<\/li>\n    <\/ul>\n\n                \t\t\t\t<h1>\n                    <span >Andy Pham<\/span>\n                <\/h1>\n                \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"bio__block m-spacer\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-5 position-relative\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"445\" src=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-445x445.jpg\" class=\"d-md-block img-fluid w-100 wp-post-image\" alt=\"Andy Pham, pastelero\" srcset=\"https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-445x445.jpg 445w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-300x300.jpg 300w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-1024x1024.jpg 1024w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-150x150.jpg 150w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-768x768.jpg 768w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-12x12.jpg 12w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-262x262.jpg 262w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham-350x350.jpg 350w, https:\/\/www.dallassymphony.org\/wp-content\/uploads\/2022\/05\/Andy-Pham.jpg 1200w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/>\t\t\t<\/div>\n\t\t\t<div class=\"col-md-7\">\n\t\t\t\t<div class=\"bio__content-wrapper\">\n\t\t\t\t\t<h1>Andy Pham<\/h1>\n\n                    <div class=\"bio__meta\">\n\t\t\t\t\t<p>Pastelero<\/p>\n                    <\/div>\n\n\t\t\t\t\t<p>Andy es un native de 24 a\u00f1os del \u00e1rea de Dallas, que tom\u00f3 su pasi\u00f3n por la pasteler\u00eda francesa y los postres europeos y la convirti\u00f3 en una aventura empresarial que trae postres modernos y de lujo a Dallas.<\/p>\n                    \t\t\t\t\t<a href=\"https:\/\/www.dallassymphony.org\/es\/people\/andy-pham\/\" class=\"a-hover\">Leer m\u00e1s<\/a>\n                                        <div class=\"share d-flex align-items-center\">\n                        \n                                            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Andy es un native de 24 a\u00f1os del \u00e1rea de Dallas, que tom\u00f3 su pasi\u00f3n por la pasteler\u00eda francesa y los postres europeos y la convirti\u00f3 en una aventura empresarial que trae postres modernos y de lujo a Dallas.<\/p>","protected":false},"featured_media":8992,"template":"","dso_musician_instrument":[],"dso_person_role":[],"class_list":["post-8990","dso_person","type-dso_person","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_person\/8990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_person"}],"about":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/types\/dso_person"}],"version-history":[{"count":0,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_person\/8990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media\/8992"}],"wp:attachment":[{"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/media?parent=8990"}],"wp:term":[{"taxonomy":"dso_musician_instrument","embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_musician_instrument?post=8990"},{"taxonomy":"dso_person_role","embeddable":true,"href":"https:\/\/www.dallassymphony.org\/es\/wp-json\/wp\/v2\/dso_person_role?post=8990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}